{"id":153,"count":12,"description":"","link":"https:\/\/robertogreco.eu\/genetealogia\/tag\/aliotta\/","name":"Aliotta","slug":"aliotta","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/robertogreco.eu\/genetealogia\/wp-json\/wp\/v2\/tags\/153","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/robertogreco.eu\/genetealogia\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/robertogreco.eu\/genetealogia\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/robertogreco.eu\/genetealogia\/wp-json\/wp\/v2\/posts?tags=153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}